{"id":231,"date":"2024-11-07T08:42:21","date_gmt":"2024-11-07T08:42:21","guid":{"rendered":"https:\/\/marc-gensane.site\/?p=231"},"modified":"2024-12-16T18:22:55","modified_gmt":"2024-12-16T18:22:55","slug":"lavenir-de-lhumanite-1e-partie-aspect-materiel","status":"publish","type":"post","link":"https:\/\/marc-gensane.site\/index.php\/2024\/11\/07\/lavenir-de-lhumanite-1e-partie-aspect-materiel\/","title":{"rendered":"L\u2019avenir de l&rsquo;humanit\u00e9. 1e partie\u00a0: aspect mat\u00e9riel"},"content":{"rendered":"\n<p style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">(novembre 2024)<\/p>\n\n\n\n<p>In\u00e9galit\u00e9s d\u2019amplitude vertigineuse ;<br>mis\u00e8res persistantes (\u00e9conomiques, politiques et morales) ;<br>guerres incessantes ;<br>d\u00e9rives de la nature (dont le climat) caus\u00e9es par l\u2019activit\u00e9 humaine \u2026<br>Tout cela nous invite vivement \u00e0 un changement d\u2019\u00e9thique, et cons\u00e9cutivement de politiques. Une transformation profonde du monde actuel est moralement n\u00e9cessaire.<\/p>\n\n\n\n<p>Mais avant d\u2019envisager ce que pourrait \u00eatre l\u2019\u00e9thique d\u2019un monde meilleur, nous en resterons dans cet article au niveau strictement mat\u00e9riel. En effet, qu\u2019on le veuille ou non, une transformation profonde nous est de toute fa\u00e7on impos\u00e9e&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>par la diminution des ressources non renouvelables sur lesquelles reposent&nbsp;<em>enti\u00e8rement<\/em>&nbsp;les \u00e9conomies des nations<\/li>\n\n\n\n<li>et par les d\u00e9rives naturelles qui r\u00e9sultent de l\u2019exploitation de ces ressources et qui menace peu ou prou notre propre survie \u00e0 long terme en m\u00eame temps que celle de la nature actuelle (quoique \u2026 la nature ne mourra sans doute pas&nbsp;; elle se transformera profond\u00e9ment&nbsp;; mais quant \u00e0 l\u2019esp\u00e8ce humaine \u2026).<\/li>\n<\/ul>\n\n\n\n<p>Les ressources non renouvelables sont les \u00e9nergies fossiles (p\u00e9trole, gaz, charbon) et les m\u00e9taux (et autres min\u00e9raux). Elles sont amen\u00e9es \u00e0 s\u2019\u00e9puiser compl\u00e8tement \u00e0 plus ou moins br\u00e8ve \u00e9ch\u00e9ance si l\u2019on en poursuit l\u2019exploitation au rythme actuel.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Cas du p\u00e9trole<\/h3>\n\n\n\n<p>En 1956, Hubbert a publi\u00e9 un mod\u00e8le de la production de p\u00e9trole (pass\u00e9e et surtout \u00e0 venir) aux USA, par une courbe en cloche, connue sous le nom de&nbsp;<strong>\u00ab courbe de Hubbert \u00bb<\/strong>&nbsp;(voir exemples sur wikipedia&nbsp;; <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Pic_de_Hubbert\">https:\/\/fr.wikipedia.org\/wiki\/Pic_de_Hubbert<\/a> ).<\/p>\n\n\n\n<p>Il est int\u00e9ressant de pr\u00e9ciser que cette courbe a \u00e9t\u00e9 v\u00e9rifi\u00e9e par la r\u00e9alit\u00e9. Mais, bien s\u00fbr, seulement jusqu\u2019\u00e0 ce que l\u2019on trouve de nouveaux gisements, et surtout l\u2019exploitation du p\u00e9trole de schiste, inconnus lorsque Hubbert a calcul\u00e9 son mod\u00e8le&nbsp;: figure 1 ci-dessous. Ce qui ne fait que reporter le pic \u00e0 plus tard. Selon Jancovici et bien d\u2019autres, le pic de production du p\u00e9trole mondial dit \u00ab\u00a0conventionnel\u00a0\u00bb a eu lieu en 2008.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Figure 1. Courbe de Hubbert et production de p\u00e9trole aux USA<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"748\" src=\"https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/Hubbert_Upper-Bound_Peak_1956-1024x748.png\" alt=\"\" class=\"wp-image-232\" style=\"width:500px;height:auto\" srcset=\"https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/Hubbert_Upper-Bound_Peak_1956-1024x748.png 1024w, https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/Hubbert_Upper-Bound_Peak_1956-300x219.png 300w, https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/Hubbert_Upper-Bound_Peak_1956-768x561.png 768w, https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/Hubbert_Upper-Bound_Peak_1956.png 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>Compte tenu essentiellement du p\u00e9trole de schiste, les \u00e9tudes du Shift Project estiment que le pic de production mondiale a eu lieu en 2018. D\u2019autres \u00e9tudes donnent environ 2025. En r\u00e9alit\u00e9 provisoire, depuis 2018, la production plafonne (apr\u00e8s le \u00ab\u00a0creux COVID\u00a0\u00bb de 2020). Et il vaudrait mieux s\u2019abstenir du p\u00e9trole de schiste, une vraie saloperie pour l\u2019environnement, en plus d\u2019une rentabilit\u00e9 tr\u00e8s contest\u00e9e.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Les ressources non renouvelables<\/h3>\n\n\n\n<p>Rappelons que le pic de production d\u2019une ressource est le moment (l\u2019ann\u00e9e) o\u00f9 sa production est \u00e0 son maximum. Ce moment co\u00efncide en g\u00e9n\u00e9ral avec celui o\u00f9 les r\u00e9serves encore disponibles et pratiquement exploitables sont \u00e9gales \u00e0 ce qui a d\u00e9j\u00e0 \u00e9t\u00e9 utilis\u00e9. On peut ainsi mod\u00e9liser toute production de toutes ressources non renouvelables par une courbe de Hubbert, et donc aussi, toute production de produits utilisant ces ressources non renouvelables.<\/p>\n\n\n\n<p>Les estimations des pics de production d\u00e9pendent naturellement des estimations que l\u2019on peut avoir sur les quantit\u00e9s totales disponibles et utilisables : celles-ci varient au fur et \u00e0 mesure des d\u00e9couvertes. En g\u00e9n\u00e9ral donc, ce pic a tendance \u00e0 reculer avec les ann\u00e9es, ce qui pourrait donner \u00e0 certains l\u2019illusion compl\u00e8tement absurde qu\u2019il reculera toujours. Le plus souvent, toutefois, les d\u00e9couvertes qui se pr\u00e9sentent et se pr\u00e9senteront encore, sont de moins en moins utilisables : de moins en moins rentables et de plus en plus polluantes.<\/p>\n\n\n\n<p>Les estimations des pics des m\u00e9taux, figure 2, sont extraits de&nbsp;: &nbsp;<a href=\"https:\/\/energieetenvironnement.com\/2021\/07\/28\/la-difficile-estimation-du-pic-des-metaux\/\">https:\/\/energieetenvironnement.com\/2021\/07\/28\/la-difficile-estimation-du-pic-des-metaux\/<\/a>.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Figure 2. Pics de production des m\u00e9taux<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"748\" height=\"618\" src=\"https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/pic-des-metaux.jpg\" alt=\"\" class=\"wp-image-233\" srcset=\"https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/pic-des-metaux.jpg 748w, https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/pic-des-metaux-300x248.jpg 300w\" sizes=\"(max-width: 748px) 100vw, 748px\" \/><\/figure><\/div>\n\n\n<p><strong><br>La moyenne brute des pics de tous ces m\u00e9taux est 2030.<\/strong><\/p>\n\n\n\n<p>Compte tenu des pics de production, de p\u00e9trole en 2018, de gaz entre aujourd&rsquo;hui et 2030, de charbon en train de plafonner depuis 10 ans : <br><strong>Dans l\u2019ensemble, nous sommes actuellement en p\u00e9riode de pics : certaines ressources ont d\u00e9j\u00e0 pass\u00e9 le leur, d\u2019autres y passeront bient\u00f4t<\/strong>.<\/p>\n\n\n\n<p>Les quantit\u00e9s disponibles de mat\u00e9riaux non renouvelables d\u00e9croissent inexorablement, et un jour ou l\u2019autre de toute fa\u00e7on il n\u2019y en aura plus gu\u00e8re. Et le mieux est de s\u2019y pr\u00e9parer d\u00e8s maintenant. S\u2019y pr\u00e9parer, et agir en cons\u00e9quence.<\/p>\n\n\n\n<p>Comme l\u2019\u00e9conomie mondiale repose presque enti\u00e8rement sur ces ressources, elle peut \u00eatre repr\u00e9sent\u00e9e par une courbe de Hubbert g\u00e9n\u00e9ralis\u00e9e&nbsp;(figure 3).<\/p>\n\n\n\n<p>La figure 3 est norm\u00e9e par son maximum. La valeur-plancher relative est la production moyenne hors \u00e8re industrielle, constante.<\/p>\n\n\n\n<p>Elle est bien s\u00fbr tr\u00e8s sch\u00e9matique&nbsp;; toutefois elle peut \u00eatre consid\u00e9r\u00e9e plus comme un \u00ab&nbsp;mod\u00e8le&nbsp;\u00bb, certes tr\u00e8s impr\u00e9cis, que comme un simple sc\u00e9nario.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><em>Figure 3. Courbe de Hubbert du volume de production mondiale (par habitant)<\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"460\" src=\"https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/Hubbert.png\" alt=\"\" class=\"wp-image-234\" srcset=\"https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/Hubbert.png 950w, https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/Hubbert-300x145.png 300w, https:\/\/marc-gensane.site\/wp-content\/uploads\/2024\/11\/Hubbert-768x372.png 768w\" sizes=\"(max-width: 950px) 100vw, 950px\" \/><\/figure><\/div>\n\n\n<p>Le probl\u00e8me qui appara\u00eet alors est le suivant :&nbsp;<strong>nous entrons dans une p\u00e9riode de transition entre<\/strong><br>&#8211; un syst\u00e8me \u00e9conomique encore consid\u00e9r\u00e9 comme actuel, qui consid\u00e8re les ressources fossiles comme infinies et gratuites (\u00ab&nbsp;croissance&nbsp;\u00bb),<br>&#8211; et un syst\u00e8me o\u00f9 il n\u2019y en aura plus et que je qualifierais de \u00ab&nbsp;post-d\u00e9croissance&nbsp;\u00bb.<br>On trouve souvent utilis\u00e9 le terme \u00ab&nbsp;post-croissance&nbsp;\u00bb pour d\u00e9signer tant\u00f4t la partie \u00ab&nbsp;d\u00e9croissance + post-d\u00e9croissance&nbsp;\u00bb, tant\u00f4t la partie \u00ab&nbsp;post-d\u00e9croissance&nbsp;\u00bb seule.<\/p>\n\n\n\n<p>Donc entre deux syst\u00e8mes \u00ab stables \u00bb : le premier, vieux de 2.5 si\u00e8cles, fond\u00e9 sur la croissance (une stabilit\u00e9 \u2026 qui s\u2019est r\u00e9v\u00e9l\u00e9e constamment instable,&nbsp;<em>tr\u00e8s<\/em>&nbsp;instable), le deuxi\u00e8me r\u00e9ellement et n\u00e9cessairement stable et sobre (la sobri\u00e9t\u00e9, \u00ab&nbsp;heureuse \u00bb autant que possible), au bout d&rsquo;une d\u00e9croissance de 2.5 si\u00e8cles (par sym\u00e9trie avec la p\u00e9riode croissante).<\/p>\n\n\n\n<p>Le premier syst\u00e8me \u00e9tant fond\u00e9 sur la \u00ab&nbsp;croissance&nbsp;\u00bb, la p\u00e9riode de transition est n\u00e9cessairement caract\u00e9ris\u00e9e par la \u00ab&nbsp;d\u00e9croissance&nbsp;\u00bb : c\u2019est le principal ph\u00e9nom\u00e8ne \u00e0 organiser, pour que lui aussi soit \u2026 stable, si possible beaucoup plus stable que la p\u00e9riode de croissance.<br>En effet, il faut rappeler la croissance a \u00e9t\u00e9 particuli\u00e8rement instable&nbsp;: guerres multiples (pas seulement les \u00ab&nbsp;mondiales&nbsp;\u00bb)&nbsp;; colonisations&nbsp;; crises&nbsp;: il n\u2019y a pas que celle de 1929, il y en a partout et tout le temps&nbsp;: pour s\u2019en convaincre, il suffit de lire par exemple le rapport de Villerm\u00e9&nbsp;<em>: Tableau de l&rsquo;\u00e9tat physique et moral des ouvriers employ\u00e9s dans les manufactures de coton, de laine et de soie<\/em> (publi\u00e9 en 1840)&nbsp;: les crises plus ou moins locales, \u00e7\u00e0 n\u2019arr\u00eate pas.<br>Par ailleurs, beaucoup sur terre ne l\u2019ont pas vue, cette croissance.<\/p>\n\n\n\n<p>Avant l\u2019\u00e2ge de bronze, on n\u2019utilisait pas du tout de ressources fossiles. Jusqu\u2019\u00e0 il y a environ 3 si\u00e8cles l\u2019humanit\u00e9 en utilisait tr\u00e8s peu : c\u2019est la 1e partie de la courbe de Hubbert, non pas nulle, mais voisine de 0 et constante.<\/p>\n\n\n\n<p>Puis s\u2019est d\u00e9velopp\u00e9e peu \u00e0 peu l\u2019\u00e8re industrielle (et financi\u00e8re et mondialis\u00e9e). Le syst\u00e8me actuel a donc mis 2 \u00e0 3 si\u00e8cles \u00e0 se construire : c\u2019est la partie ascendante de la courbe de Hubbert.<\/p>\n\n\n\n<p>Selon cette m\u00eame courbe, partie descendante, il en mettrait autant \u00e0 se d\u00e9-construire (et non pas se d\u00e9truire, on esp\u00e8re). Est-ce \u00e0 dire que l\u2019on reviendra au moyen-\u00e2ge ? Non certes, car si tout se passe bien, l\u2019humanit\u00e9 aura conserv\u00e9 les connaissances scientifiques acquises et encore \u00e0 venir, et toutes les ressources non renouvelables qu\u2019elle aura su garder et recycler. La \u00ab\u00a0post-d\u00e9croissance\u00a0\u00bb connaitrait une production relativement voisine de 0, et constante.<\/p>\n\n\n\n<p><strong>Le mod\u00e8le de Hubbert peut s\u2019appliquer \u00e0 toute production particuli\u00e8re<\/strong>. Supposons que nous soyons actuellement en p\u00e9riode g\u00e9n\u00e9rale de pics de productions, comme c\u2019est le cas pour le p\u00e9trole et les m\u00e9taux.<br><strong>Exemples\u00a0:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019automobile existe \u00e0 grande \u00e9chelle depuis environ 110 ans (la \u00ab\u00a0Ford T\u00a0\u00bb). Elle dispara\u00eetrait donc dans 110 ans.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019\u00e9lectricit\u00e9 existe depuis environ 140 ans (Thomas Edison). On aurait encore pour 140 ans d\u2019\u00e9lectricit\u00e9 \u2013 d\u00e9croissante \u2013 et peut-\u00eatre un peu plus si on arrive \u00e0 maintenir les barrages.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019informatique existe depuis environ 80 ans. Elle durerait donc encore 80 ans, en usage d\u00e9croissant\u00a0: le \u00ab\u00a0tout-informatis\u00e9\u00a0\u00bb n\u2019en a plus pour tr\u00e8s longtemps. Et encore moins pour l\u2019ordinateur portable (50 ans), le t\u00e9l\u00e9phone portable (40 ans), et encore moins pour le \u00ab\u00a0smartphone\u00a0\u00bb (20 ans).<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L\u2019aviation de ligne existe depuis environ 70 ans. On en aurait donc encore au maximum pour 70 ans, voire moins en cas de d\u00e9carbonation s\u00e9rieuse de nos productions.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La mondialisation a commenc\u00e9 il y a environ 500 ans, et existe de mani\u00e8re de plus en plus envahissante surtout depuis 250 ans. Compte tenu de la baisse des ressources \u00e9nerg\u00e9tiques, elle commence \u00e0 \u00eatre touch\u00e9e d\u00e8s maintenant, au moins par endroits. Elle en a donc encore pour 250 ans au maximum.<\/li>\n\n\n\n<li>Les populations des plus grandes villes sont amen\u00e9es \u00e0 baisser r\u00e9guli\u00e8rement, m\u00eame si elles n&rsquo;en prennent pas encore le chemin.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Et peut-\u00eatre la population mondiale sera-elle concern\u00e9e. Elle n\u2019a pas encore atteint son maximum possible, mais elle cro\u00eet d\u00e9j\u00e0 partout moins vite. Et si la d\u00e9croissance &#8211; in\u00e9vitable, rappelons-le encore &#8211; se produit dans le d\u00e9sordre, avec conflits, guerres, maladies, famines, elle pourrait bien d\u00e9cro\u00eetre: 1 milliard au d\u00e9but de la croissance; retour \u00e0 1 milliard d&rsquo;ici quelques si\u00e8cles ou moins (cf. Mathieu Ricard: <a href=\"https:\/\/www.youtube.com\/watch?v=PPJSiLEtDb8\">https:\/\/www.youtube.com\/watch?v=PPJSiLEtDb8<\/a>)<\/li>\n<\/ul>\n\n\n\n<p><strong>Nota bene : Le sch\u00e9ma (presque idyllique) de Hubbert suppose toutes conditions naturelles inchang\u00e9es. Supposition certes peu r\u00e9aliste, du fait des d\u00e9rives in\u00e9luctables et peu pr\u00e9visibles&nbsp;desdites conditions naturelles (la nature dans son ensemble &#8211; la d\u00e9rive du climat n&rsquo;\u00e9tant que l&rsquo;un des facteurs).<\/strong><br><\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">Discussion de ce sc\u00e9nario<\/h3>\n\n\n\n<p>La d\u00e9croissance peut \u00eatre plus rapide ou plus lente que le mod\u00e8le de la figure 3.<\/p>\n\n\n\n<p><strong>Plus rapide<\/strong> :<\/p>\n\n\n\n<p>Si l\u2019on veut s\u2019attaquer vraiment et s\u00e9rieusement aux probl\u00e8mes environnementaux, dans une relative urgence&nbsp;: la d\u00e9rive climatique, certes. Et tous les autres qui sont plus importants&nbsp;: ce sont les diverses destructions, d\u00e9j\u00e0 cit\u00e9es&nbsp;: celles de la nature dans son ensemble, animaux, v\u00e9g\u00e9taux, destructions des sols (cultiv\u00e9s ou non), d\u00e9chets et pollutions physiques et mentales. Mentales, car l\u2019humain est en train de se d\u00e9truire par des intoxications mentales&nbsp;; trop de \u00ab&nbsp;progr\u00e8s&nbsp;\u00bb tue le progr\u00e8s.<\/p>\n\n\n\n<p>Plus rapide s\u2019il s\u2019av\u00e8re que le reste des ressources s\u2019av\u00e8re de moins en moins rentable,&nbsp; de plus en plus difficile d\u2019acc\u00e8s, et de plus en plus polluant.<\/p>\n\n\n\n<p><strong>Plus lente<\/strong> par deux voies:<\/p>\n\n\n\n<p>Compte tenu de la n\u00e9cessit\u00e9 de freiner la d\u00e9rive du climat et de la nature, il serait tr\u00e8s utile d\u2019acc\u00e9l\u00e9rer la d\u00e9croissance d\u00e8s maintenant. Actuellement on est encore au voisinage du pic, donc \u00e0 pente presque nulle. Or on a calcul\u00e9 (\u00ab on \u00bb : voir Jancovici par exemple) que, pour atteindre l\u2019objectif officiel de r\u00e9chauffement inf\u00e9rieur \u00e0 2\u00b0, il faudrait diminuer les \u00e9missions de gaz \u00e0 effet de serre de 5% par an pendant 30 ans. R\u00e9aliser une telle pente de d\u00e9croissance d\u00e8s maintenant, aurait le grand int\u00e9r\u00eat suivant : l\u2019\u00e9puisement serait report\u00e9&nbsp; plus loin, que si l\u2019on commence avec une pente presque nulle comme le sugg\u00e8re la courbe en cloche de Hubbert au point de passage au pic. L\u2019autre cons\u00e9quence est qu\u2019il en r\u00e9sulterait au bout de ces 30 ans une division par 5 de cette consommation d\u2019\u00e9nergie carbon\u00e9e (et celle du PIB moyen mondial n&rsquo;en serait pas loin), ce que certains pourraient trouver difficile \u00e0 admettre. C\u2019est pourtant une n\u00e9cessit\u00e9 (seulement, bien s\u00fbr, si l\u2019on veut \u00e9viter de plus grandes difficult\u00e9s).<\/p>\n\n\n\n<p>L\u2019autre voie est le recyclage. Pour mesurer son efficacit\u00e9, il faudrait consid\u00e9rer,&nbsp;pour un produit donn\u00e9 en instance de d\u00e9chet : 1) le rendement de recyclage, rapport de la quantit\u00e9 en sortie de l\u2019op\u00e9ration, \u00e0 la quantit\u00e9 entr\u00e9e&nbsp;; 2) le taux de recyclage, rapport de la quantit\u00e9 amen\u00e9e au recyclage \u00e0 la quantit\u00e9 totale en instance de d\u00e9chet&nbsp;; 3) le rendement \u00e9nerg\u00e9tique, rapport de l\u2019\u00e9nergie de recyclage \u00e0 l\u2019\u00e9nergie de production initiale du produit (extraction et raffinage).<\/p>\n\n\n\n<p>Je ne me lance pas dans une analyse pr\u00e9cise des propri\u00e9t\u00e9s de recyclage des divers \u00e9l\u00e9ments. Celles-ci sont extr\u00eamement variables, complexes, et \u00e9volutives. Ainsi certains m\u00e9taux ont un rendement de recyclage de pr\u00e8s de 100% (acier, aluminium, cuivre)&nbsp;; vous pourrez avoir des casseroles en aluminium encore pendant des si\u00e8cles et des si\u00e8cles. D\u2019autres ont un rendement faible, notamment certains de ceux qui entrent dans la fabrication des \u00e9quipements num\u00e9riques et de certains \u00e9quipements \u00e9lectriques (batteries par exemple).<br>Les rendements \u00e9nerg\u00e9tiques sont souvent bons, ce qui est un bon point pour les \u00e9conomies d\u2019\u00e9nergies, donc la lutte pour l\u2019environnement.<br>Dans l\u2019ensemble, les taux de recyclage sont \u00e9lev\u00e9s pour les produits faciles \u00e0 recycler, et restent bas pour les autres jusqu\u2019\u00e0 apparition \u00e9ventuelle de nouvelles techniques. Aucun n\u2019atteint et ne peut atteindre 100%.<\/p>\n\n\n\n<p>Donc quoi qu\u2019il en soit, l\u2019\u00e8re de la post-d\u00e9croissance est probablement in\u00e9vitable, et certainement souhaitable pour raisons environnementales. Elle se compte en si\u00e8cles, cela peut nous para\u00eetre lointain, mais c\u2019est in\u00e9luctable. Peut-\u00eatre ne pouvons-nous pas encore bien l\u2019imaginer, mais en attendant, il urge de planifier et r\u00e9aliser la d\u00e9croissance. Notamment en misant sur ce que Jancovici appelle les \u00ab&nbsp;ralentisseurs de d\u00e9croissance&nbsp;\u00bb&nbsp;: l\u2019\u00e9nergie nucl\u00e9aire, les recyclages.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">La post-d\u00e9croissance<\/h3>\n\n\n\n<p>Ebauchons quelques caract\u00e9ristiques mat\u00e9rielles de l\u2019\u00e9poque, lointaine&nbsp;(?), \u00e0 venir, l\u2019\u00e9poque \u00ab&nbsp;post-d\u00e9croissance&nbsp;\u00bb (derni\u00e8re partie de la courbe de Hubbert, voisine de 0), attendue d\u2019ici 2 ou 3 si\u00e8cles, ou plus, ou moins. A cette \u00e9poque, les ressources non renouvelables ou non exploitables auront \u00e9t\u00e9 \u00e9puis\u00e9es. Cette \u00e9poque n\u2019utilise plus que des ressources enti\u00e8rement renouvelables ; et aussi ce qui aura pu \u00eatre r\u00e9cup\u00e9r\u00e9 des recyclages de produits utilisant des ressources fossiles, en supposant que l\u2019on a pu les porter \u00e0 leur maximum possible.<\/p>\n\n\n\n<p>Energie&nbsp;: le bois, l\u2019eau, le vent, le soleil. On a vu que l\u2019on pouvait se chauffer au bois (voir par exemple&nbsp;: <a href=\"https:\/\/marc-gensane.site\/index.php\/2024\/08\/31\/chauffage-au-bois\/\">Chauffage au bois \u2013 Perceptions et perspectives<\/a>), avec mod\u00e9ration car le bois est n\u00e9cessaire pour d&rsquo;autres usages indispensables. <br>On ne pourra plus trop compter sur les techniques&nbsp;<em>actuelles<\/em>&nbsp;d\u2019\u00e9olien et de solaire, qui utilisent des mat\u00e9riaux non renouvelables et ne sont pas ce que l\u2019on appelle \u00ab&nbsp;pilotables&nbsp;\u00bb, car d\u00e9pendant de sources al\u00e9atoires. Pour ce qui est de l\u2019\u00e9lectricit\u00e9, il resterait surtout l\u2019eau, soit actuellement 20 % de la production actuelle mondiale, ce qui n\u2019est pas n\u00e9gligeable (mais sans oublier que la maintenance des barrages n\u00e9cessite des mat\u00e9riaux non renouvelables, et peut-\u00eatre pas tous bien recyclables &#8230;).<\/p>\n\n\n\n<p>Un jour o\u00f9 l\u2019autre, l\u2019humanit\u00e9 retournera \u00e0 la bougie \u2026.<\/p>\n\n\n\n<p>Mat\u00e9riaux de construction&nbsp;: la pierre et la brique (non renouvelables, certes, mais il y en a encore beaucoup, et partiellement recyclables: c&rsquo;est ainsi que l&rsquo;on a pu d\u00e9molir d&rsquo;anciens b\u00e2timents en pierre pour se construire des maisons) ; le bois ; la paille et le chanvre (torchis : tr\u00e8s bon mat\u00e9riau isolant) \u2026<\/p>\n\n\n\n<p>V\u00eatement&nbsp;: textile agricole. En France : le lin, la laine, les peaux de b\u00eates; la viscose?&nbsp;; et quand il fait chaud, la feuille de vigne.<\/p>\n\n\n\n<p>Sant\u00e9&nbsp;: surtout, les m\u00e9dicaments tir\u00e9s directement des plantes m\u00e9dicinales. Mais surtout et premi\u00e8rement : l\u2019hygi\u00e8ne physique et mentale. Un exemple&nbsp;parlant : pour ce que l\u2019on peut en conna\u00eetre, les philosophes de l\u2019Antiquit\u00e9 grecque, sans la m\u00e9decine moderne mais avec certainement une bonne hygi\u00e8ne de vie, avaient une \u00ab esp\u00e9rance de vie \u00bb de pr\u00e8s de 80 ans, gu\u00e8re moins que les fran\u00e7ais actuellement (qui sont plut\u00f4t parmi les mieux lotis en ce domaine).<\/p>\n\n\n\n<p>Alimentation&nbsp;: malgr\u00e9 les d\u00e9rives de la nature et du climat, on ose esp\u00e9rer que cela ne posera pas encore de probl\u00e8me&nbsp;<strong><em>en moyenne<\/em><\/strong>&nbsp;dans les ann\u00e9es qui viennent (voir par exemple&nbsp;<a href=\"https:\/\/marc-gensane.site\/index.php\/2024\/02\/29\/87\/\">Combien d\u2019hommes la Terre peut-elle nourrir ? \u2013 Perceptions et perspectives<\/a> ). Mais les d\u00e9rives de la nature sont enclanch\u00e9es, ne dispara\u00eetront pas de sit\u00f4t m\u00eame si nous devenons subitement raisonnables, donc l&rsquo;avenir agricole reste incertain.<\/p>\n\n\n\n<p>Economie&nbsp;bas\u00e9e sur \u2026 les \u00e9conomies ; r\u00e9duction drastique des transports, des industries ; disparition des multinationales et des grandes entreprises, ainsi que de la bourse et des placements de rentiers, de la grande distribution avec ses rayons pl\u00e9thoriques \u2026, fin de la \u00ab&nbsp;mondialisation&nbsp;\u00bb. Au profit du re-d\u00e9veloppement de l\u2019artisanat local, et d\u2019une agriculture \u00e9cologique.<\/p>\n\n\n\n<p>Baisse sensible du pouvoir d\u2019achat moyen (je dis bien : moyen ; cela implique une r\u00e9duction drastique des in\u00e9galit\u00e9s \u2013 si toutefois on ne souhaite pas le chaos).<\/p>\n\n\n\n<p>Une prudence \u00e9l\u00e9mentaire demande l\u2019application du principe d\u2019<strong>autonomie maximum<\/strong>&nbsp;au moins pour les besoins vitaux, et \u00e0 l\u2019\u00e9chelon aussi local que possible (maximum ne veut pas dire totale, ce qui ne serait ni possible ni souhaitable&nbsp;: <strong>Autonomie n\u2019est pas autarcie<\/strong>) : nourriture, logement (et son contenu), v\u00eatement, sant\u00e9. A l\u2019\u00e9chelon local :&nbsp; arr\u00eater d\u2019augmenter la taille des grandes villes, mais la diminuer au maximum possible ; comme disait Alphonse Allais : \u00ab b\u00e2tir les villes \u00e0 la campagne \u00bb.<\/p>\n\n\n\n<p>Energie r\u00e9duite implique : le minimum possible de transports, donc&nbsp;<strong>circuits courts<\/strong>, ce qui implique aussi l\u2019autonomie maximum locale, et pour tous les besoins et utilit\u00e9s.<\/p>\n\n\n\n<p>Mati\u00e8re premi\u00e8re r\u00e9duite implique : fabrications solides et durables, facilement r\u00e9parables, donc simples, sans sophistications (technologies dites \u00ab&nbsp;light&nbsp;\u00bb); produits compl\u00e8tement (ou presque) recyclables ; ce qui est incompatible avec la logique du capitalisme de croissance. Sachant aussi que les op\u00e9rations de recyclages n\u00e9cessitent eux-m\u00eames de l\u2019\u00e9nergie et des mat\u00e9riaux fossiles (du moins, pour ce que l\u2019on sait faire actuellement).<\/p>\n\n\n\n<p>Pour une transition en douceur, \u00e0 titre provisoire : \u00e9nergie nucl\u00e9aire, agro-carburants (qui devraient c\u00e9der la place aux cultures vitales en cas d\u2019augmentation de la population).&nbsp;<br>A propos des dangers du nucl\u00e9aire : ils font peur, mais ne paraissent statistiquement pas plus dangereux que les autres ; les dangers ne sont simplement pas les m\u00eames.&nbsp;<br>Le probl\u00e8me, c\u2019est la grande industrie en g\u00e9n\u00e9ral.<br>Vous connaissez le dicton :&nbsp;<em>petits enfants, petits soucis ; grands enfants, grands soucis<\/em>.<br>En paraphrasant :<br><em>Petite industrie, petits dangers ; grosse industrie, gros dangers<\/em>. Quelle que soit l\u2019industrie.<\/p>\n\n\n\n<p><strong>En conclusion : Il s\u2019agit d\u2019assumer et organiser la fin du \u00ab r\u00e8gne de la quantit\u00e9 \u00bb&nbsp;<\/strong>(titre d\u2019un ouvrage de Ren\u00e9 Gu\u00e9non)<strong>.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(novembre 2024) In\u00e9galit\u00e9s d\u2019amplitude vertigineuse ;mis\u00e8res persistantes (\u00e9conomiques, politiques et morales) ;guerres incessantes ;d\u00e9rives de la nature (dont le climat) caus\u00e9es par l\u2019activit\u00e9 humaine \u2026Tout cela nous invite vivement \u00e0 un changement d\u2019\u00e9thique, et cons\u00e9cutivement de politiques. Une transformation profonde du monde actuel est moralement n\u00e9cessaire. Mais avant d\u2019envisager ce que pourrait \u00eatre l\u2019\u00e9thique d\u2019un&hellip;&nbsp;<a href=\"https:\/\/marc-gensane.site\/index.php\/2024\/11\/07\/lavenir-de-lhumanite-1e-partie-aspect-materiel\/\" rel=\"bookmark\">Lire la suite &raquo;<span class=\"screen-reader-text\">L\u2019avenir de l&rsquo;humanit\u00e9. 1e partie\u00a0: aspect mat\u00e9riel<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"categories":[2],"tags":[15,13,6],"class_list":["post-231","post","type-post","status-publish","format-standard","hentry","category-pour-un-monde-meilleur","tag-decroissance","tag-economie","tag-monde-meilleur"],"_links":{"self":[{"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/posts\/231"}],"collection":[{"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/comments?post=231"}],"version-history":[{"count":10,"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/posts\/231\/revisions"}],"predecessor-version":[{"id":398,"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/posts\/231\/revisions\/398"}],"wp:attachment":[{"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/media?parent=231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/categories?post=231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/marc-gensane.site\/index.php\/wp-json\/wp\/v2\/tags?post=231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}